{"id":1372,"count":1,"description":"","link":"https:\/\/blog.truebluehealer.com\/index.php\/tag\/evil-rulers\/","name":"evil rulers","slug":"evil-rulers","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags\/1372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/posts?tags=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}