{"id":428,"count":1,"description":"","link":"https:\/\/blog.truebluehealer.com\/index.php\/tag\/outrage-marxism\/","name":"Outrage Marxism","slug":"outrage-marxism","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/posts?tags=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}