{"id":6470,"count":1,"description":"","link":"https:\/\/blog.truebluehealer.com\/index.php\/tag\/aboriginal-violence\/","name":"aboriginal violence","slug":"aboriginal-violence","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags\/6470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/posts?tags=6470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}