{"id":8033,"count":1,"description":"","link":"https:\/\/blog.truebluehealer.com\/index.php\/tag\/paris-climate-debunked\/","name":"Paris climate debunked","slug":"paris-climate-debunked","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags\/8033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.truebluehealer.com\/index.php\/wp-json\/wp\/v2\/posts?tags=8033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}